{"id":4776,"date":"2024-11-22T15:47:21","date_gmt":"2024-11-22T14:47:21","guid":{"rendered":"https:\/\/www.horn-wzm.de\/shop\/unkategorisiert\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\/"},"modified":"2024-11-22T15:47:21","modified_gmt":"2024-11-22T14:47:21","slug":"werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163","status":"publish","type":"product","link":"https:\/\/www.horn-wzm.de\/pa\/shop\/werkzeughalter\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\/","title":{"rendered":"\u0a1f\u0a42\u0a32 \u0a39\u0a4b\u0a32\u0a21\u0a30 STAR 7.077.408 3-\u0a35\u0a47\u0a05 \u0a21\u0a4d\u0a30\u0a3f\u0a32 \u0a39\u0a4b\u0a32\u0a21\u0a30 \u00d832mm \u0a15\u0a42\u0a32\u0a48\u0a02\u0a1f \u0a38\u0a2a\u0a32\u0a3e\u0a08 \u0a26\u0a47 \u0a28\u0a3e\u0a32 (\u0a07\u0a70\u0a1f\u0a30\u0a28\u0a48\u0a38\u0a3c\u0a28\u0a32 \u0a28\u0a70\u0a2c\u0a30 231163)"},"content":{"rendered":"<p><b>\u0a38\u0a25\u0a3e\u0a28:<\/b> \u0a1c\u0a30\u0a2e\u0a28\u0a40, \u0a2c\u0a3e\u0a21\u0a47\u0a28-\u0a35\u0a41\u0a30\u0a1f\u0a2e\u0a2c\u0a30\u0a17 \u0a26\u0a71\u0a16\u0a23-\u0a2a\u0a71\u0a1b\u0a2e<\/p>\n<p><b>\u0a39\u0a3e\u0a32\u0a24:<\/b> \u0a28\u0a35\u0a47\u0a02 \u0a1c\u0a3f\u0a70\u0a28\u0a3e \u0a35\u0a27\u0a40\u0a06<\/p>\n<p><b>\u0a28\u0a3f\u0a30\u0a2e\u0a3e\u0a24\u0a3e:<\/b> \u0a28\u0a39\u0a40\u0a02<\/p>\n<p><b>\u0a2e\u0a3e\u0a21\u0a32:<\/b> 431-03-00<\/p>\n<p>\u0a15\u0a42\u0a32\u0a48\u0a02\u0a1f \u0a38\u0a2a\u0a32\u0a3e\u0a08 \u0a26\u0a47 \u0a28\u0a3e\u0a32 \u0a1f\u0a4d\u0a30\u0a3f\u0a2a\u0a32 \u0a21\u0a4d\u0a30\u0a3f\u0a32 \u0a39\u0a4b\u0a32\u0a21\u0a30 \u00d832mm (\u0a05\u0a70\u0a26\u0a30\u0a42\u0a28\u0a40 \u0a1c\u0a3e\u0a02 \u0a2c\u0a3e\u0a39\u0a30\u0a40)<br \/>\n\u0a2e\u0a41\u0a71\u0a16 \u0a05\u0a24\u0a47 \u0a15\u0a3e\u0a0a\u0a02\u0a1f\u0a30 \u0a38\u0a2a\u0a3f\u0a70\u0a21\u0a32 \u0a32\u0a08 (IntNr231163)<br \/>\n7.077.408<br \/>\n\u0a39\u0a47\u0a20 \u0a32\u0a3f\u0a16\u0a40\u0a06\u0a02 STAR \u0a2e\u0a38\u0a3c\u0a40\u0a28 \u0a15\u0a3f\u0a38\u0a2e\u0a3e\u0a02 \u0a32\u0a08 \u0a22\u0a41\u0a15\u0a35\u0a3e\u0a02:<br \/>\nSV-12\/20\/20R\/32\/32J\/32J II\/38R \u2013 ECAS-20T\/30T<\/p>\n<p>\u0a24\u0a15\u0a28\u0a40\u0a15\u0a40 \u0a21\u0a47\u0a1f\u0a3e \u0a05\u0a24\u0a47 \u0a1c\u0a3e\u0a23\u0a15\u0a3e\u0a30\u0a40 \u0a26\u0a47 \u0a28\u0a3e\u0a32-\u0a28\u0a3e\u0a32 \u0a2a\u0a39\u0a3f\u0a32\u0a3e\u0a02 \u0a26\u0a40 \u0a35\u0a3f\u0a15\u0a30\u0a40 \u0a35\u0a3f\u0a71\u0a1a \u0a24\u0a2c\u0a26\u0a40\u0a32\u0a40\u0a06\u0a02 \u0a05\u0a24\u0a47 \u0a17\u0a32\u0a24\u0a40\u0a06\u0a02 \u0a26\u0a47 \u0a05\u0a27\u0a40\u0a28!<\/p>\n<p>\u0a15\u0a42\u0a32\u0a48\u0a02\u0a1f \u0a38\u0a2a\u0a32\u0a3e\u0a08 \u0a26\u0a47 \u0a28\u0a3e\u0a32 3-\u0a2b\u0a4b\u0a32\u0a21 \u0a21\u0a4d\u0a30\u0a3f\u0a32 \u0a39\u0a4b\u0a32\u0a21\u0a30 \u00d832mm (\u0a05\u0a70\u0a26\u0a30\u0a42\u0a28\u0a40 \u0a1c\u0a3e\u0a02 \u0a2c\u0a3e\u0a39\u0a30\u0a40)<br \/>\n\u0a2e\u0a41\u0a71\u0a16 \u0a05\u0a24\u0a47 \u0a15\u0a3e\u0a0a\u0a02\u0a1f\u0a30 \u0a38\u0a2a\u0a3f\u0a70\u0a21\u0a32 \u0a32\u0a08 (IntNr231163)<br \/>\n7.077.408<br \/>\n\u0a39\u0a47\u0a20 \u0a32\u0a3f\u0a16\u0a40\u0a06\u0a02 STAR \u0a2e\u0a38\u0a3c\u0a40\u0a28 \u0a15\u0a3f\u0a38\u0a2e\u0a3e\u0a02 \u0a32\u0a08 \u0a22\u0a41\u0a15\u0a35\u0a3e\u0a02:<br \/>\nSV-12\/20\/20R\/32\/32J\/32J II\/38R \u2013 ECAS-20T\/30T<\/p>\n<p>\u0a24\u0a15\u0a28\u0a40\u0a15\u0a40 \u0a21\u0a47\u0a1f\u0a3e \u0a05\u0a24\u0a47 \u0a1c\u0a3e\u0a23\u0a15\u0a3e\u0a30\u0a40 \u0a26\u0a47 \u0a28\u0a3e\u0a32-\u0a28\u0a3e\u0a32 \u0a35\u0a3f\u0a15\u0a30\u0a40 \u0a24\u0a4b\u0a02 \u0a2a\u0a39\u0a3f\u0a32\u0a3e\u0a02 \u0a24\u0a2c\u0a26\u0a40\u0a32\u0a40\u0a06\u0a02 \u0a05\u0a24\u0a47 \u0a17\u0a32\u0a24\u0a40\u0a06\u0a02 \u0a26\u0a47 \u0a05\u0a27\u0a40\u0a28!<\/p>","protected":false},"excerpt":{"rendered":"<p>Standort: Deutschland, Baden-W\u00fcrttemberg S\u00fcdwest Zustand: Neuwertig Hersteller: n.a. Modell: 431-03-00 3-fach-Bohrhalter \u00d832mm mit K\u00fchlmittelversorgung (intern oder extern) f\u00fcr Haupt- und Gegensspindel (IntNr231163) 7.077.408 Passend f\u00fcr folgende STAR-Maschinentypen: SV-12\/20\/20R\/32\/32J\/32J II\/38R &#8211; ECAS-20T\/30T Aenderungen und Irrtuemer in den technischen Daten und Angaben sowie Zwischenverkauf vorbehalten! 3-fold drill holder \u00d832mm with coolant supply (internal or external) for main [&hellip;]<\/p>\n","protected":false},"featured_media":4775,"template":"","meta":[],"product_brand":[],"product_cat":[84],"product_tag":[],"class_list":["post-4776","product","type-product","status-publish","has-post-thumbnail","product_cat-werkzeughalter","first","instock","taxable","shipping-taxable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Standort: Deutschland, Baden-W\u00fcrttemberg S\u00fcdwestZustand: NeuwertigHersteller: n.a.Modell: 431-03-003-fach-Bohrhalter \u00d832mm mit K\u00fchlmittelversorgung (intern oder extern) f\u00fcr Haupt- und Gegensspindel (IntNr231163) 7.077.408 Passend f\u00fcr folgende STAR-Maschinentypen: SV-12\/20\/20R\/32\/32J\/32J II\/38R - ECAS-20T\/30T Aenderungen und Irrtuemer in den technischen Daten und Angaben sowie Zwischenverkauf vorbehalten! 3-fold drill holder \u00d832mm with coolant supply (internal or external) for main and counter spindle (IntNr231163)\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.horn-wzm.de\/pa\/shop\/werkzeughalter\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"pa_IN\" \/>\n\t\t<meta property=\"og:site_name\" content=\"HORN Werkzeugmaschinen -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Werkzeughalter STAR 7.077.408 3-fach-Bohrhalter \u00d832mm mit K\u00fchlmittelversorgung (IntNr231163) - HORN Werkzeugmaschinen\" \/>\n\t\t<meta property=\"og:description\" content=\"Standort: Deutschland, Baden-W\u00fcrttemberg S\u00fcdwestZustand: NeuwertigHersteller: n.a.Modell: 431-03-003-fach-Bohrhalter \u00d832mm mit K\u00fchlmittelversorgung (intern oder extern) f\u00fcr Haupt- und Gegensspindel (IntNr231163) 7.077.408 Passend f\u00fcr folgende STAR-Maschinentypen: SV-12\/20\/20R\/32\/32J\/32J II\/38R - ECAS-20T\/30T Aenderungen und Irrtuemer in den technischen Daten und Angaben sowie Zwischenverkauf vorbehalten! 3-fold drill holder \u00d832mm with coolant supply (internal or external) for main and counter spindle (IntNr231163)\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.horn-wzm.de\/pa\/shop\/werkzeughalter\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.horn-wzm.de\/wp-content\/uploads\/2022\/09\/cropped-New-Project-2.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.horn-wzm.de\/wp-content\/uploads\/2022\/09\/cropped-New-Project-2.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-11-22T14:47:21+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-11-22T14:47:21+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Werkzeughalter STAR 7.077.408 3-fach-Bohrhalter \u00d832mm mit K\u00fchlmittelversorgung (IntNr231163) - HORN Werkzeugmaschinen\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Standort: Deutschland, Baden-W\u00fcrttemberg S\u00fcdwestZustand: NeuwertigHersteller: n.a.Modell: 431-03-003-fach-Bohrhalter \u00d832mm mit K\u00fchlmittelversorgung (intern oder extern) f\u00fcr Haupt- und Gegensspindel (IntNr231163) 7.077.408 Passend f\u00fcr folgende STAR-Maschinentypen: SV-12\/20\/20R\/32\/32J\/32J II\/38R - ECAS-20T\/30T Aenderungen und Irrtuemer in den technischen Daten und Angaben sowie Zwischenverkauf vorbehalten! 3-fold drill holder \u00d832mm with coolant supply (internal or external) for main and counter spindle (IntNr231163)\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.horn-wzm.de\/wp-content\/uploads\/2022\/09\/cropped-New-Project-2.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\\\/shop\\\/werkzeughalter\\\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\\\/?page_id=3015#listItem\",\"name\":\"Unsere Maschinen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\\\/?page_id=3015#listItem\",\"position\":2,\"name\":\"Unsere Maschinen\",\"item\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\\\/?page_id=3015\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\\\/produkt-kategorie\\\/werkzeughalter\\\/#listItem\",\"name\":\"Werkzeughalter\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\\\/produkt-kategorie\\\/werkzeughalter\\\/#listItem\",\"position\":3,\"name\":\"Werkzeughalter\",\"item\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\\\/produkt-kategorie\\\/werkzeughalter\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\\\/shop\\\/werkzeughalter\\\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\\\/#listItem\",\"name\":\"Werkzeughalter STAR 7.077.408 3-fach-Bohrhalter \\u00d832mm mit K\\u00fchlmittelversorgung (IntNr231163)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\\\/?page_id=3015#listItem\",\"name\":\"Unsere Maschinen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\\\/shop\\\/werkzeughalter\\\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\\\/#listItem\",\"position\":4,\"name\":\"Werkzeughalter STAR 7.077.408 3-fach-Bohrhalter \\u00d832mm mit K\\u00fchlmittelversorgung (IntNr231163)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\\\/produkt-kategorie\\\/werkzeughalter\\\/#listItem\",\"name\":\"Werkzeughalter\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\\\/shop\\\/werkzeughalter\\\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\\\/#itempage\",\"url\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\\\/shop\\\/werkzeughalter\\\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\\\/\",\"name\":\"Werkzeughalter STAR 7.077.408 3-fach-Bohrhalter \\u00d832mm mit K\\u00fchlmittelversorgung (IntNr231163) - HORN Werkzeugmaschinen\",\"description\":\"Standort: Deutschland, Baden-W\\u00fcrttemberg S\\u00fcdwestZustand: NeuwertigHersteller: n.a.Modell: 431-03-003-fach-Bohrhalter \\u00d832mm mit K\\u00fchlmittelversorgung (intern oder extern) f\\u00fcr Haupt- und Gegensspindel (IntNr231163) 7.077.408 Passend f\\u00fcr folgende STAR-Maschinentypen: SV-12\\\/20\\\/20R\\\/32\\\/32J\\\/32J II\\\/38R - ECAS-20T\\\/30T Aenderungen und Irrtuemer in den technischen Daten und Angaben sowie Zwischenverkauf vorbehalten! 3-fold drill holder \\u00d832mm with coolant supply (internal or external) for main and counter spindle (IntNr231163)\",\"inLanguage\":\"pa-IN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\\\/shop\\\/werkzeughalter\\\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.horn-wzm.de\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/intnr231163-1-scaled.jpg\",\"@id\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\\\/shop\\\/werkzeughalter\\\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\\\/#mainImage\",\"width\":2560,\"height\":1813},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\\\/shop\\\/werkzeughalter\\\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\\\/#mainImage\"},\"datePublished\":\"2024-11-22T15:47:21+01:00\",\"dateModified\":\"2024-11-22T15:47:21+01:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\\\/#organization\",\"name\":\"HORN Werkzeugmaschinen Horn Werkzeugmaschinen\",\"description\":\"Horn Werkzeugmaschinen ist ein deutsches Handelshaus f\\u00fcr Werkzeugmaschinen und CNC-Technik. Das Unternehmen ist auf den Handel und die Vermittlung neuer und gebrauchter Produktionsanlagen spezialisiert.\",\"url\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\\\/\",\"telephone\":\"+491713350427\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.horn-wzm.de\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Symbol-schwarz-gross-scaled.jpg\",\"@id\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\\\/shop\\\/werkzeughalter\\\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\\\/#organizationLogo\",\"width\":2560,\"height\":2560},\"image\":{\"@id\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\\\/shop\\\/werkzeughalter\\\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\\\/#website\",\"url\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\\\/\",\"name\":\"HORN Werkzeugmaschinen\",\"inLanguage\":\"pa-IN\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.horn-wzm.de\\\/pa\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u0a1f\u0a42\u0a32 \u0a39\u0a4b\u0a32\u0a21\u0a30 STAR 7.077.408 3-\u0a35\u0a47\u0a05 \u0a21\u0a4d\u0a30\u0a3f\u0a32 \u0a39\u0a4b\u0a32\u0a21\u0a30 \u00d832mm \u0a15\u0a42\u0a32\u0a48\u0a02\u0a1f \u0a38\u0a2a\u0a32\u0a3e\u0a08 \u0a26\u0a47 \u0a28\u0a3e\u0a32 (\u0a07\u0a70\u0a1f\u0a30\u0a28\u0a48\u0a38\u0a3c\u0a28\u0a32 \u0a28\u0a70\u0a2c\u0a30 231163) - HORN \u0a2e\u0a38\u0a3c\u0a40\u0a28 \u0a1f\u0a42\u0a32\u0a38","description":"Standort: Deutschland, Baden-W\u00fcrttemberg S\u00fcdwestZustand: NeuwertigHersteller: n.a.Modell: 431-03-003-fach-Bohrhalter \u00d832mm mit K\u00fchlmittelversorgung (intern oder extern) f\u00fcr Haupt- und Gegensspindel (IntNr231163) 7.077.408 Passend f\u00fcr folgende STAR-Maschinentypen: SV-12\/20\/20R\/32\/32J\/32J II\/38R - ECAS-20T\/30T Aenderungen und Irrtuemer in den technischen Daten und Angaben sowie Zwischenverkauf vorbehalten! 3-fold drill holder \u00d832mm with coolant supply (internal or external) for main and counter spindle (IntNr231163)","canonical_url":"https:\/\/www.horn-wzm.de\/pa\/shop\/werkzeughalter\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.horn-wzm.de\/pa\/shop\/werkzeughalter\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.horn-wzm.de\/pa#listItem","position":1,"name":"Home","item":"https:\/\/www.horn-wzm.de\/pa","nextItem":{"@type":"ListItem","@id":"https:\/\/www.horn-wzm.de\/pa\/?page_id=3015#listItem","name":"Unsere Maschinen"}},{"@type":"ListItem","@id":"https:\/\/www.horn-wzm.de\/pa\/?page_id=3015#listItem","position":2,"name":"Unsere Maschinen","item":"https:\/\/www.horn-wzm.de\/pa\/?page_id=3015","nextItem":{"@type":"ListItem","@id":"https:\/\/www.horn-wzm.de\/pa\/produkt-kategorie\/werkzeughalter\/#listItem","name":"Werkzeughalter"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.horn-wzm.de\/pa#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.horn-wzm.de\/pa\/produkt-kategorie\/werkzeughalter\/#listItem","position":3,"name":"Werkzeughalter","item":"https:\/\/www.horn-wzm.de\/pa\/produkt-kategorie\/werkzeughalter\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.horn-wzm.de\/pa\/shop\/werkzeughalter\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\/#listItem","name":"Werkzeughalter STAR 7.077.408 3-fach-Bohrhalter \u00d832mm mit K\u00fchlmittelversorgung (IntNr231163)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.horn-wzm.de\/pa\/?page_id=3015#listItem","name":"Unsere Maschinen"}},{"@type":"ListItem","@id":"https:\/\/www.horn-wzm.de\/pa\/shop\/werkzeughalter\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\/#listItem","position":4,"name":"Werkzeughalter STAR 7.077.408 3-fach-Bohrhalter \u00d832mm mit K\u00fchlmittelversorgung (IntNr231163)","previousItem":{"@type":"ListItem","@id":"https:\/\/www.horn-wzm.de\/pa\/produkt-kategorie\/werkzeughalter\/#listItem","name":"Werkzeughalter"}}]},{"@type":"ItemPage","@id":"https:\/\/www.horn-wzm.de\/pa\/shop\/werkzeughalter\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\/#itempage","url":"https:\/\/www.horn-wzm.de\/pa\/shop\/werkzeughalter\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\/","name":"Werkzeughalter STAR 7.077.408 3-fach-Bohrhalter \u00d832mm mit K\u00fchlmittelversorgung (IntNr231163) - HORN Werkzeugmaschinen","description":"Standort: Deutschland, Baden-W\u00fcrttemberg S\u00fcdwestZustand: NeuwertigHersteller: n.a.Modell: 431-03-003-fach-Bohrhalter \u00d832mm mit K\u00fchlmittelversorgung (intern oder extern) f\u00fcr Haupt- und Gegensspindel (IntNr231163) 7.077.408 Passend f\u00fcr folgende STAR-Maschinentypen: SV-12\/20\/20R\/32\/32J\/32J II\/38R - ECAS-20T\/30T Aenderungen und Irrtuemer in den technischen Daten und Angaben sowie Zwischenverkauf vorbehalten! 3-fold drill holder \u00d832mm with coolant supply (internal or external) for main and counter spindle (IntNr231163)","inLanguage":"pa-IN","isPartOf":{"@id":"https:\/\/www.horn-wzm.de\/pa\/#website"},"breadcrumb":{"@id":"https:\/\/www.horn-wzm.de\/pa\/shop\/werkzeughalter\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.horn-wzm.de\/wp-content\/uploads\/2024\/11\/intnr231163-1-scaled.jpg","@id":"https:\/\/www.horn-wzm.de\/pa\/shop\/werkzeughalter\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\/#mainImage","width":2560,"height":1813},"primaryImageOfPage":{"@id":"https:\/\/www.horn-wzm.de\/pa\/shop\/werkzeughalter\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\/#mainImage"},"datePublished":"2024-11-22T15:47:21+01:00","dateModified":"2024-11-22T15:47:21+01:00"},{"@type":"Organization","@id":"https:\/\/www.horn-wzm.de\/pa\/#organization","name":"HORN Werkzeugmaschinen Horn Werkzeugmaschinen","description":"Horn Werkzeugmaschinen ist ein deutsches Handelshaus f\u00fcr Werkzeugmaschinen und CNC-Technik. Das Unternehmen ist auf den Handel und die Vermittlung neuer und gebrauchter Produktionsanlagen spezialisiert.","url":"https:\/\/www.horn-wzm.de\/pa\/","telephone":"+491713350427","logo":{"@type":"ImageObject","url":"https:\/\/www.horn-wzm.de\/wp-content\/uploads\/2026\/01\/Symbol-schwarz-gross-scaled.jpg","@id":"https:\/\/www.horn-wzm.de\/pa\/shop\/werkzeughalter\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\/#organizationLogo","width":2560,"height":2560},"image":{"@id":"https:\/\/www.horn-wzm.de\/pa\/shop\/werkzeughalter\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/www.horn-wzm.de\/pa\/#website","url":"https:\/\/www.horn-wzm.de\/pa\/","name":"HORN Werkzeugmaschinen","inLanguage":"pa-IN","publisher":{"@id":"https:\/\/www.horn-wzm.de\/pa\/#organization"}}]},"og:locale":"pa_IN","og:site_name":"HORN Werkzeugmaschinen -","og:type":"article","og:title":"Werkzeughalter STAR 7.077.408 3-fach-Bohrhalter \u00d832mm mit K\u00fchlmittelversorgung (IntNr231163) - HORN Werkzeugmaschinen","og:description":"Standort: Deutschland, Baden-W\u00fcrttemberg S\u00fcdwestZustand: NeuwertigHersteller: n.a.Modell: 431-03-003-fach-Bohrhalter \u00d832mm mit K\u00fchlmittelversorgung (intern oder extern) f\u00fcr Haupt- und Gegensspindel (IntNr231163) 7.077.408 Passend f\u00fcr folgende STAR-Maschinentypen: SV-12\/20\/20R\/32\/32J\/32J II\/38R - ECAS-20T\/30T Aenderungen und Irrtuemer in den technischen Daten und Angaben sowie Zwischenverkauf vorbehalten! 3-fold drill holder \u00d832mm with coolant supply (internal or external) for main and counter spindle (IntNr231163)","og:url":"https:\/\/www.horn-wzm.de\/pa\/shop\/werkzeughalter\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\/","og:image":"https:\/\/www.horn-wzm.de\/wp-content\/uploads\/2022\/09\/cropped-New-Project-2.png","og:image:secure_url":"https:\/\/www.horn-wzm.de\/wp-content\/uploads\/2022\/09\/cropped-New-Project-2.png","article:published_time":"2024-11-22T14:47:21+00:00","article:modified_time":"2024-11-22T14:47:21+00:00","twitter:card":"summary_large_image","twitter:title":"Werkzeughalter STAR 7.077.408 3-fach-Bohrhalter \u00d832mm mit K\u00fchlmittelversorgung (IntNr231163) - HORN Werkzeugmaschinen","twitter:description":"Standort: Deutschland, Baden-W\u00fcrttemberg S\u00fcdwestZustand: NeuwertigHersteller: n.a.Modell: 431-03-003-fach-Bohrhalter \u00d832mm mit K\u00fchlmittelversorgung (intern oder extern) f\u00fcr Haupt- und Gegensspindel (IntNr231163) 7.077.408 Passend f\u00fcr folgende STAR-Maschinentypen: SV-12\/20\/20R\/32\/32J\/32J II\/38R - ECAS-20T\/30T Aenderungen und Irrtuemer in den technischen Daten und Angaben sowie Zwischenverkauf vorbehalten! 3-fold drill holder \u00d832mm with coolant supply (internal or external) for main and counter spindle (IntNr231163)","twitter:image":"https:\/\/www.horn-wzm.de\/wp-content\/uploads\/2022\/09\/cropped-New-Project-2.png"},"aioseo_meta_data":{"post_id":"4776","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-01-19 17:05:01","updated":"2026-01-19 17:05:01","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.horn-wzm.de\/pa\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.horn-wzm.de\/pa\/?page_id=3015\" title=\"Unsere Maschinen\">Unsere Maschinen<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.horn-wzm.de\/pa\/produkt-kategorie\/werkzeughalter\/\" title=\"Werkzeughalter\">Werkzeughalter<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tWerkzeughalter STAR 7.077.408 3-fach-Bohrhalter \u00d832mm mit K\u00fchlmittelversorgung (IntNr231163)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.horn-wzm.de\/pa"},{"label":"Unsere Maschinen","link":"https:\/\/www.horn-wzm.de\/pa\/?page_id=3015"},{"label":"Werkzeughalter","link":"https:\/\/www.horn-wzm.de\/pa\/produkt-kategorie\/werkzeughalter\/"},{"label":"Werkzeughalter STAR 7.077.408 3-fach-Bohrhalter \u00d832mm mit K\u00fchlmittelversorgung (IntNr231163)","link":"https:\/\/www.horn-wzm.de\/pa\/shop\/werkzeughalter\/werkzeughalter-star-7-077-408-3-fach-bohrhalter-o32mm-mit-kuehlmittelversorgung-intnr231163\/"}],"_links":{"self":[{"href":"https:\/\/www.horn-wzm.de\/pa\/wp-json\/wp\/v2\/product\/4776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.horn-wzm.de\/pa\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.horn-wzm.de\/pa\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/www.horn-wzm.de\/pa\/wp-json\/wp\/v2\/product\/4776\/revisions"}],"predecessor-version":[{"id":4777,"href":"https:\/\/www.horn-wzm.de\/pa\/wp-json\/wp\/v2\/product\/4776\/revisions\/4777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.horn-wzm.de\/pa\/wp-json\/wp\/v2\/media\/4775"}],"wp:attachment":[{"href":"https:\/\/www.horn-wzm.de\/pa\/wp-json\/wp\/v2\/media?parent=4776"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.horn-wzm.de\/pa\/wp-json\/wp\/v2\/product_brand?post=4776"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.horn-wzm.de\/pa\/wp-json\/wp\/v2\/product_cat?post=4776"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.horn-wzm.de\/pa\/wp-json\/wp\/v2\/product_tag?post=4776"}],"curies":[{"name":"\u0a21\u0a2c\u0a32\u0a2f\u0a42\u0a2a\u0a40","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}